{"id":5432,"date":"2019-04-01T20:53:10","date_gmt":"2019-04-01T18:53:10","guid":{"rendered":"https:\/\/monodes.com\/predaelli\/?p=5432"},"modified":"2019-04-01T20:53:10","modified_gmt":"2019-04-01T18:53:10","slug":"non-ci-tange","status":"publish","type":"post","link":"https:\/\/monodes.com\/predaelli\/2019\/04\/01\/non-ci-tange\/","title":{"rendered":"Non ci tange"},"content":{"rendered":"<p>Leggo con un sorriso questo articolo \u201c<a href=\"https:\/\/www.dday.it\/redazione\/30332\/piersilvio-mal-consigliato-lo-switch-off-rischia-di-affondare-la-corazzata-mediaset?fbclid=IwAR0jwIYm2E9gGBIAP12z8g5LBFGdUEByvQFGL_EwNVyqnV1lDxiJ_yAJgPk\">Piersilvio mal consigliato: lo switch off rischia di affondare la corazzata Mediaset<\/a>\u201e.<\/p>\n<p>Gi\u00e0 perch\u00e9 da molto tempo oramai in casa mia non guardiamo pi\u00f9 trasmissioni televisive di alcun tipo.<\/p>\n<p>Abbiamo la fortuna di abitare vicino alla biblioteca comunale che fa parte del circuito bibliotecario brianzolo. Possiamo prenotare prestiti da qualsiasi biblioteca del circuito dal loro comodo sito. Le risorse pubbliche destinate allo scopo sono ottimamente spese.<\/p>\n<p>Grazie al Cielo mia moglie ha letto tantissimi libri assieme alle mie figlie fin da prima di andare a scuola. Leggere sul lettone tutti assieme \u00e8 diventato una delle nostre attivit\u00e0 preferite ed anche ora che la maggiore \u00e8 in prima media e la seconda \u00e8 in quarta elementare abbiamo mantenuto questa abitudine.<\/p>\n<p>Non solo: entrambe sono diventate avide lettrici, tanto che la maggiore ha &#8220;divorato&#8221; Lo Hobbit in una decina di giorni. Durante la scuola s&#8217;intende. Non vi dico quanto ci ha messo a leggere tutti i libri di Harry Potter, potreste non crederci.<\/p>\n<p>Oh certo qualche documentario e qualche film li guardiamo. Presi dalle mediateche comunali. Al momento non sentiamo proprio il bisogno di spender soldi per cose come Netflix o Amazon TV o qualsivoglia servizio analogo.<\/p>\n<p>Per questo notizie come queste mi fanno sorridere.<\/p>\n<p>Perch\u00e9 i libri son molto spesso pi\u00f9 belli dei film e delle serie TV. E lo scrivo io che in giovent\u00f9 ho macinato centinaia di serie di &#8220;cartoni animati&#8221; (lo so che si chiamano &#8220;anime&#8221;, ma nel profondo uso ancora la vecchia terminologia).<\/p>\n<p>Al momento gli unici video che guardiamo son su YouTube. Io documentari di matematica, loro video di lavoretti o cose simili.<\/p>\n<p>Di questo uso assai morigerato della TV devo ringraziare mia moglie che ha investito davvero tanto tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Leggo con un sorriso questo articolo \u201cPiersilvio mal consigliato: lo switch off rischia di affondare la corazzata Mediaset\u201e. Gi\u00e0 perch\u00e9 da molto tempo oramai in casa mia non guardiamo pi\u00f9 trasmissioni televisive di alcun tipo. Abbiamo la fortuna di abitare vicino alla biblioteca comunale che fa parte del circuito bibliotecario brianzolo. Possiamo prenotare prestiti da&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/monodes.com\/predaelli\/2019\/04\/01\/non-ci-tange\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_members_access_role":[],"_members_access_error":""},"categories":[19],"tags":[],"class_list":["post-5432","post","type-post","status-publish","format-standard","hentry","category-mood"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6daft-1pC","jetpack-related-posts":[{"id":11986,"url":"https:\/\/monodes.com\/predaelli\/2024\/10\/14\/il-testamento-spirituale-di-sammy-basso-vatican-news\/","url_meta":{"origin":5432,"position":0},"title":"Il testamento spirituale di Sammy Basso &#8211; Vatican News","author":"Paolo Redaelli","date":"2024-10-14","format":false,"excerpt":"Leggo solo ora\u00a0Il testamento spirituale di Sammy Basso Toccante. Il testamento spirituale di Sammy Basso Pubblichiamo il testo dello scritto del giovane biologo, simbolo della lotta alla progeria, morto il 5 ottobre, letto integralmente dal vescovo di Vicenza alle esequie celebrate oggi a Tezze sul Brenta Carissimi, Se state leggendo\u2026","rel":"","context":"In &quot;Senza categoria&quot;","block_context":{"text":"Senza categoria","link":"https:\/\/monodes.com\/predaelli\/category\/senza-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2024\/10\/cq5dam.thumbnail.cropped.1500.844.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2024\/10\/cq5dam.thumbnail.cropped.1500.844.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2024\/10\/cq5dam.thumbnail.cropped.1500.844.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2024\/10\/cq5dam.thumbnail.cropped.1500.844.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2024\/10\/cq5dam.thumbnail.cropped.1500.844.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15025,"url":"https:\/\/monodes.com\/predaelli\/2026\/02\/11\/ci-vado-io\/","url_meta":{"origin":5432,"position":1},"title":"Ci vado io","author":"Paolo Redaelli","date":"2026-02-11","format":false,"excerpt":"Inchiesta Glovo a Milano: pagati 2,50\u20ac a consegna. Tronfio di aver sempre evitato come la peste questi servizi di consegna a domicilio (Glovo, Just Eat, Foodora, Deliveroo) : non voglio essere complice di questa forma moderna e strisciante di schiavit\u00f9. Se voglio una pizza da asporto me la vado a\u2026","rel":"","context":"In &quot;Ethics&quot;","block_context":{"text":"Ethics","link":"https:\/\/monodes.com\/predaelli\/category\/ethics\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9379,"url":"https:\/\/monodes.com\/predaelli\/2022\/05\/14\/la-vera-anima-delleuropa\/","url_meta":{"origin":5432,"position":2},"title":"La vera anima dell&#8217;Europa","author":"Paolo Redaelli","date":"2022-05-14","format":false,"excerpt":"Questa sera mi sto attardando per spostare tutto lo spostabile dal vecchio telefono della mia dolce met\u00e0 - un Asus Zenfone - ad un nuovo Samsumg Galaxy A22. Erano tre-quattro mesi che iniziava ad avere \"qualche acciacco\" ma ora l'altoparlante della parte telefonica ha semplicemente smesso di telefonare. E purtroppo\u2026","rel":"","context":"In &quot;Ethics&quot;","block_context":{"text":"Ethics","link":"https:\/\/monodes.com\/predaelli\/category\/ethics\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/RDxZ_WIZ29yys\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3539,"url":"https:\/\/monodes.com\/predaelli\/2017\/12\/02\/bargle-linfame\/","url_meta":{"origin":5432,"position":3},"title":"Bargle l&#8217;infame","author":"Paolo Redaelli","date":"2017-12-02","format":"link","excerpt":"Rolling Dice: Bargle l'infame - Parte 1 e Parte 2 (Bargle e Aleena): effetto nostalgia. In noi giocatori di D&D che abbiamo iniziato con la scatola rossa il nome di Bargle, evoca piacevoli ricordi di eroiche avventure. Il mago, soprannominato L\u2019infame, \u00e8 protagonista dell\u2019avventura introduttiva che si trova tra le\u2026","rel":"","context":"In &quot;Senza categoria&quot;","block_context":{"text":"Senza categoria","link":"https:\/\/monodes.com\/predaelli\/category\/senza-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/monodes.com\/predaelli\/wp-content\/uploads\/sites\/4\/2017\/12\/Aleena-2-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3584,"url":"https:\/\/monodes.com\/predaelli\/2017\/12\/19\/doggerland-il-paradiso-scomparso-storia-controstoria\/","url_meta":{"origin":5432,"position":4},"title":"Doggerland, il paradiso scomparso &#8211; Storia &#8230;&#8230; Controstoria","author":"Paolo Redaelli","date":"2017-12-19","format":false,"excerpt":"Doggerland, il paradiso scomparso - Storia ...... Controstoria Nell\u2019Europa del nord prima del diluvio Doggerland: un nome ancora poco conosciuto. Il nome di una terra scomparsa. Da molti decenni, ormai, le reti a strascico dei pescatori del Mare del Nord portano a galla ossa di uri, mammut, renne, creature preistoriche\u2026","rel":"","context":"In &quot;Senza categoria&quot;","block_context":{"text":"Senza categoria","link":"https:\/\/monodes.com\/predaelli\/category\/senza-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6128,"url":"https:\/\/monodes.com\/predaelli\/2019\/10\/01\/ha-ancora-senso-chiamarci-ingegneri-ha-ancora-senso-iscriverci-a-un-albo\/","url_meta":{"origin":5432,"position":5},"title":"Ha ancora senso chiamarci ingegneri ? ha ancora senso iscriverci a un albo ?","author":"Paolo Redaelli","date":"2019-10-01","format":"quote","excerpt":"Ha ancora senso chiamarci ingegneri ? ha ancora senso iscriverci a un albo ? Ha ancora senso chiamarci ingegneri ? ha ancora senso iscriverci a un albo ? I Consigli Nazionali devono fare scelte coerenti per il futuro delle Professioni, ma quali Professioni vogliamo per il futuro ? Andrea Dari\u2026","rel":"","context":"In &quot;Ethics&quot;","block_context":{"text":"Ethics","link":"https:\/\/monodes.com\/predaelli\/category\/ethics\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/posts\/5432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/comments?post=5432"}],"version-history":[{"count":0,"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/posts\/5432\/revisions"}],"wp:attachment":[{"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/media?parent=5432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/categories?post=5432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monodes.com\/predaelli\/wp-json\/wp\/v2\/tags?post=5432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}